{"id":1051,"date":"2026-02-03T10:21:14","date_gmt":"2026-02-03T09:21:14","guid":{"rendered":"https:\/\/wwsu.de\/?page_id=1051"},"modified":"2026-02-03T10:22:48","modified_gmt":"2026-02-03T09:22:48","slug":"bungee-run-vermietung","status":"publish","type":"page","link":"https:\/\/warendorfer-su.de\/index.php\/verein\/bungee-run-vermietung\/","title":{"rendered":"Bungee-Run Vermietung"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Vereine und Menschen mit Spa\u00df an Bewegung aufgepasst: Ab sofort k\u00f6nnt ihr unser Bungee-Run ausleihen..<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Bungee was?<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Bungee Run ist ein Spielger\u00e4t, bei dem die Teilnehmer mit einem H\u00fcftgurt an Gummiseilen befestigt werden und mit dieser Befestigung versuchen, weiter zu laufen als der Mitspieler. Dieses spa\u00df-, aber auch schwei\u00dftreibende Spielger\u00e4t wird wie bei H\u00fcpfburgen mit einem Dauer-Luftgebl\u00e4se betrieben.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ihr wollt das WSU-Bungee Run f\u00fcr Euer Sport-Fest oder Eure private Veranstaltung ausleihen? Anbei findet Ihr weitere Informationen zu unseren Miet-Modalit\u00e4ten (Preise, Miet-Laufzeiten, Verantwortungsbereiche u. v. m.).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/wwsu.de\/wp-content\/uploads\/2026\/02\/WSU-Vertrag-zur-Ueberlassung-des-Bungee-RUN-MUSTER.pdf\" data-type=\"attachment\" data-id=\"1056\">Weitere Infos<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/wwsu.de\/wp-content\/uploads\/2026\/02\/IMG-20200308-WA0007-1024x768.jpg\" alt=\"\" class=\"wp-image-1058\" srcset=\"https:\/\/warendorfer-su.de\/wp-content\/uploads\/2026\/02\/IMG-20200308-WA0007-1024x768.jpg 1024w, https:\/\/warendorfer-su.de\/wp-content\/uploads\/2026\/02\/IMG-20200308-WA0007-300x225.jpg 300w, https:\/\/warendorfer-su.de\/wp-content\/uploads\/2026\/02\/IMG-20200308-WA0007-768x576.jpg 768w, https:\/\/warendorfer-su.de\/wp-content\/uploads\/2026\/02\/IMG-20200308-WA0007-1536x1152.jpg 1536w, https:\/\/warendorfer-su.de\/wp-content\/uploads\/2026\/02\/IMG-20200308-WA0007-400x300.jpg 400w, https:\/\/warendorfer-su.de\/wp-content\/uploads\/2026\/02\/IMG-20200308-WA0007.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/wwsu.de\/wp-content\/uploads\/2026\/02\/IMG-20200308-WA0009-1024x768.jpg\" alt=\"\" class=\"wp-image-1059\" srcset=\"https:\/\/warendorfer-su.de\/wp-content\/uploads\/2026\/02\/IMG-20200308-WA0009-1024x768.jpg 1024w, https:\/\/warendorfer-su.de\/wp-content\/uploads\/2026\/02\/IMG-20200308-WA0009-300x225.jpg 300w, https:\/\/warendorfer-su.de\/wp-content\/uploads\/2026\/02\/IMG-20200308-WA0009-768x576.jpg 768w, https:\/\/warendorfer-su.de\/wp-content\/uploads\/2026\/02\/IMG-20200308-WA0009-1536x1153.jpg 1536w, https:\/\/warendorfer-su.de\/wp-content\/uploads\/2026\/02\/IMG-20200308-WA0009-400x300.jpg 400w, https:\/\/warendorfer-su.de\/wp-content\/uploads\/2026\/02\/IMG-20200308-WA0009.jpg 1599w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/wwsu.de\/wp-content\/uploads\/2026\/02\/IMG-20200308-WA0005-1024x768.jpg\" alt=\"\" class=\"wp-image-1060\" srcset=\"https:\/\/warendorfer-su.de\/wp-content\/uploads\/2026\/02\/IMG-20200308-WA0005-1024x768.jpg 1024w, https:\/\/warendorfer-su.de\/wp-content\/uploads\/2026\/02\/IMG-20200308-WA0005-300x225.jpg 300w, https:\/\/warendorfer-su.de\/wp-content\/uploads\/2026\/02\/IMG-20200308-WA0005-768x576.jpg 768w, https:\/\/warendorfer-su.de\/wp-content\/uploads\/2026\/02\/IMG-20200308-WA0005-1536x1152.jpg 1536w, https:\/\/warendorfer-su.de\/wp-content\/uploads\/2026\/02\/IMG-20200308-WA0005-400x300.jpg 400w, https:\/\/warendorfer-su.de\/wp-content\/uploads\/2026\/02\/IMG-20200308-WA0005.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Vereine und Menschen mit Spa\u00df an Bewegung aufgepasst: Ab sofort k\u00f6nnt ihr unser Bungee-Run ausleihen.. Bungee was? Bungee Run ist ein Spielger\u00e4t, bei dem die Teilnehmer mit einem H\u00fcftgurt an Gummiseilen befestigt werden und mit dieser Befestigung versuchen, weiter zu &hellip; <a href=\"https:\/\/warendorfer-su.de\/index.php\/verein\/bungee-run-vermietung\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"parent":273,"menu_order":6,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-1051","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bungee-Run Vermietung - Warendorfer Sportunion 1895\/1972 e.V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/warendorfer-su.de\/index.php\/verein\/bungee-run-vermietung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bungee-Run Vermietung - Warendorfer Sportunion 1895\/1972 e.V.\" \/>\n<meta property=\"og:description\" content=\"Vereine und Menschen mit Spa\u00df an Bewegung aufgepasst: Ab sofort k\u00f6nnt ihr unser Bungee-Run ausleihen.. Bungee was? Bungee Run ist ein Spielger\u00e4t, bei dem die Teilnehmer mit einem H\u00fcftgurt an Gummiseilen befestigt werden und mit dieser Befestigung versuchen, weiter zu &hellip; Weiterlesen &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/warendorfer-su.de\/index.php\/verein\/bungee-run-vermietung\/\" \/>\n<meta property=\"og:site_name\" content=\"Warendorfer Sportunion 1895\/1972 e.V.\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-03T09:22:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/warendorfer-su.de\/wp-content\/uploads\/2026\/02\/IMG-20200308-WA0007.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/warendorfer-su.de\\\/index.php\\\/verein\\\/bungee-run-vermietung\\\/\",\"url\":\"https:\\\/\\\/warendorfer-su.de\\\/index.php\\\/verein\\\/bungee-run-vermietung\\\/\",\"name\":\"Bungee-Run Vermietung - Warendorfer Sportunion 1895\\\/1972 e.V.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/warendorfer-su.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/warendorfer-su.de\\\/index.php\\\/verein\\\/bungee-run-vermietung\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/warendorfer-su.de\\\/index.php\\\/verein\\\/bungee-run-vermietung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wwsu.de\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/IMG-20200308-WA0007-1024x768.jpg\",\"datePublished\":\"2026-02-03T09:21:14+00:00\",\"dateModified\":\"2026-02-03T09:22:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/warendorfer-su.de\\\/index.php\\\/verein\\\/bungee-run-vermietung\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/warendorfer-su.de\\\/index.php\\\/verein\\\/bungee-run-vermietung\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/warendorfer-su.de\\\/index.php\\\/verein\\\/bungee-run-vermietung\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wwsu.de\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/IMG-20200308-WA0007-1024x768.jpg\",\"contentUrl\":\"https:\\\/\\\/wwsu.de\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/IMG-20200308-WA0007-1024x768.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/warendorfer-su.de\\\/index.php\\\/verein\\\/bungee-run-vermietung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/warendorfer-su.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Verein\",\"item\":\"https:\\\/\\\/warendorfer-su.de\\\/index.php\\\/verein\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bungee-Run Vermietung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/warendorfer-su.de\\\/#website\",\"url\":\"https:\\\/\\\/warendorfer-su.de\\\/\",\"name\":\"Warendorfer Sportunion 1895\\\/1972 e.V.\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/warendorfer-su.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/warendorfer-su.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/warendorfer-su.de\\\/#organization\",\"name\":\"Warendorfer Sportunion 1895\\\/1972 e.V.\",\"url\":\"https:\\\/\\\/warendorfer-su.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/warendorfer-su.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/warendorfer-su.de\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/WSU-Vector.png\",\"contentUrl\":\"https:\\\/\\\/warendorfer-su.de\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/WSU-Vector.png\",\"width\":851,\"height\":851,\"caption\":\"Warendorfer Sportunion 1895\\\/1972 e.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/warendorfer-su.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bungee-Run Vermietung - Warendorfer Sportunion 1895\/1972 e.V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/warendorfer-su.de\/index.php\/verein\/bungee-run-vermietung\/","og_locale":"de_DE","og_type":"article","og_title":"Bungee-Run Vermietung - Warendorfer Sportunion 1895\/1972 e.V.","og_description":"Vereine und Menschen mit Spa\u00df an Bewegung aufgepasst: Ab sofort k\u00f6nnt ihr unser Bungee-Run ausleihen.. Bungee was? Bungee Run ist ein Spielger\u00e4t, bei dem die Teilnehmer mit einem H\u00fcftgurt an Gummiseilen befestigt werden und mit dieser Befestigung versuchen, weiter zu &hellip; Weiterlesen &rarr;","og_url":"https:\/\/warendorfer-su.de\/index.php\/verein\/bungee-run-vermietung\/","og_site_name":"Warendorfer Sportunion 1895\/1972 e.V.","article_modified_time":"2026-02-03T09:22:48+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/warendorfer-su.de\/wp-content\/uploads\/2026\/02\/IMG-20200308-WA0007.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/warendorfer-su.de\/index.php\/verein\/bungee-run-vermietung\/","url":"https:\/\/warendorfer-su.de\/index.php\/verein\/bungee-run-vermietung\/","name":"Bungee-Run Vermietung - Warendorfer Sportunion 1895\/1972 e.V.","isPartOf":{"@id":"https:\/\/warendorfer-su.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/warendorfer-su.de\/index.php\/verein\/bungee-run-vermietung\/#primaryimage"},"image":{"@id":"https:\/\/warendorfer-su.de\/index.php\/verein\/bungee-run-vermietung\/#primaryimage"},"thumbnailUrl":"https:\/\/wwsu.de\/wp-content\/uploads\/2026\/02\/IMG-20200308-WA0007-1024x768.jpg","datePublished":"2026-02-03T09:21:14+00:00","dateModified":"2026-02-03T09:22:48+00:00","breadcrumb":{"@id":"https:\/\/warendorfer-su.de\/index.php\/verein\/bungee-run-vermietung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/warendorfer-su.de\/index.php\/verein\/bungee-run-vermietung\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/warendorfer-su.de\/index.php\/verein\/bungee-run-vermietung\/#primaryimage","url":"https:\/\/wwsu.de\/wp-content\/uploads\/2026\/02\/IMG-20200308-WA0007-1024x768.jpg","contentUrl":"https:\/\/wwsu.de\/wp-content\/uploads\/2026\/02\/IMG-20200308-WA0007-1024x768.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/warendorfer-su.de\/index.php\/verein\/bungee-run-vermietung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/warendorfer-su.de\/"},{"@type":"ListItem","position":2,"name":"Verein","item":"https:\/\/warendorfer-su.de\/index.php\/verein\/"},{"@type":"ListItem","position":3,"name":"Bungee-Run Vermietung"}]},{"@type":"WebSite","@id":"https:\/\/warendorfer-su.de\/#website","url":"https:\/\/warendorfer-su.de\/","name":"Warendorfer Sportunion 1895\/1972 e.V.","description":"","publisher":{"@id":"https:\/\/warendorfer-su.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/warendorfer-su.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/warendorfer-su.de\/#organization","name":"Warendorfer Sportunion 1895\/1972 e.V.","url":"https:\/\/warendorfer-su.de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/warendorfer-su.de\/#\/schema\/logo\/image\/","url":"https:\/\/warendorfer-su.de\/wp-content\/uploads\/2025\/12\/WSU-Vector.png","contentUrl":"https:\/\/warendorfer-su.de\/wp-content\/uploads\/2025\/12\/WSU-Vector.png","width":851,"height":851,"caption":"Warendorfer Sportunion 1895\/1972 e.V."},"image":{"@id":"https:\/\/warendorfer-su.de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/warendorfer-su.de\/index.php\/wp-json\/wp\/v2\/pages\/1051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/warendorfer-su.de\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/warendorfer-su.de\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/warendorfer-su.de\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/warendorfer-su.de\/index.php\/wp-json\/wp\/v2\/comments?post=1051"}],"version-history":[{"count":6,"href":"https:\/\/warendorfer-su.de\/index.php\/wp-json\/wp\/v2\/pages\/1051\/revisions"}],"predecessor-version":[{"id":1061,"href":"https:\/\/warendorfer-su.de\/index.php\/wp-json\/wp\/v2\/pages\/1051\/revisions\/1061"}],"up":[{"embeddable":true,"href":"https:\/\/warendorfer-su.de\/index.php\/wp-json\/wp\/v2\/pages\/273"}],"wp:attachment":[{"href":"https:\/\/warendorfer-su.de\/index.php\/wp-json\/wp\/v2\/media?parent=1051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}